{"id":119,"date":"2021-07-14T05:54:41","date_gmt":"2021-07-14T05:54:41","guid":{"rendered":"https:\/\/aura-agency-eg.com\/index.php\/home\/"},"modified":"2026-06-28T10:50:29","modified_gmt":"2026-06-28T10:50:29","slug":"home","status":"publish","type":"page","link":"https:\/\/aura-agency-eg.com\/","title":{"rendered":"Home"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"119\" class=\"elementor elementor-119\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-980baac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"980baac\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5e47e22\" data-id=\"5e47e22\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f3b5a86 elementor-widget elementor-widget-text-editor\" data-id=\"f3b5a86\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a style=\"color: #ffffff00; font-size: 1pt; line-height: 2pt; height: auto; position: absolute;\" href=\"https:\/\/1-win-oynay.com\/\">1 win<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5cef52 aux-appear-watch-animation aux-scale-up elementor-widget elementor-widget-aux_modern_heading\" data-id=\"e5cef52\" data-element_type=\"widget\" data-widget_type=\"aux_modern_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"aux-widget-modern-heading\">\n            <div class=\"aux-widget-inner\"><h5 class=\"aux-modern-heading-primary\">We Are Taking You To A New World Of E-Marketing<\/h5><h2 class=\"aux-modern-heading-secondary\"><span class=\"aux-head-highlight\">Aura Advertising Agency<\/span><\/h2><div class=\"aux-modern-heading-description\">At aura advertising agency we are offers end-to-end solutions for your online presence, from branding your business, designing your website and optimizing it for higher rankings in search engine results to creating and executing complete digital marketing strategy for you. Providing anything and everything from an overall strategy to content marketing, social media advertising, pay-per-click (PPC) campaigns, influencer marketing, PR services, and much more.\n<div style=\"overflow:hidden;height:1px\"><a href=\"http:\/\/www.grandedoner.com\/\">7 slots<\/a><\/div>\n<div style=\"overflow:hidden;height:1px\"><a href=\"https:\/\/www.pomsky-alaskankleekai-minihusky.com\/\">abebet<\/a><\/div><\/div><\/div>\n        <\/section>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ba2644 elementor-widget elementor-widget-text-editor\" data-id=\"7ba2644\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a style=\"color: #ffffff00; font-size: 1pt; line-height: 2pt; height: auto; position: absolute;\" href=\"https:\/\/mostbet-uzb-online.com\/\">mostbet uz casino<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"aux-scroll-anim elementor-element elementor-element-a7f972b elementor-widget__width-auto aux-appear-watch-animation aux-fade-in-up-2 elementor-widget elementor-widget-aux_image\" data-move-in=\"moveHorizontal\" data-move-out=\"moveHorizontal\" data-axis-x=\"5\" data-axis-y=\"200\" data-rotate=\"90\" data-scale=\"1\" data-vp-top=\"0.5\" data-vp-bot=\"0.5\" data-el-top=\"0.2\" data-scroll-animation-off=\"1024\" data-id=\"a7f972b\" data-element_type=\"widget\" data-widget_type=\"aux_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-image aux-alignnone aux-parent-au3c65febb\">\n    <div class=\"aux-media-hint-frame \">\n        <div class=\"aux-media-image \" >\n        \n            \n\n            \n            <img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"98\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/Pencil-L.png\" class=\"aux-attachment aux-featured-image aux-attachment-id-83\" alt=\"demo-attachment-278-Pencil-L\" data-ratio=\"0.66\" data-original-w=\"65\" \/>            \n                <\/div>\n    <\/div>\n\n<\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85a51e6 elementor-widget__width-auto aux-appear-watch-animation aux-fade-in-right elementor-widget elementor-widget-aux_modern_button\" data-id=\"85a51e6\" data-element_type=\"widget\" data-widget_type=\"aux_modern_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t    <div class=\"aux-modern-button-wrapper aux-modern-button-align-left\" >\n                    <a class=\"aux-modern-button aux-black aux-modern-button-md aux-modern-button-normal aux-modern-button-default aux-icon-\" href=\"tel:+201011332871\">\n                <div class=\"aux-overlay\"><\/div>\n                                    <div class=\"aux-icon \">\n                                            <\/div>\n                                <div class=\"aux-text\">\n<span class=\"aux-text-before\">get start today<\/span>                <\/div>\n            <\/a>\n            \n    <\/div>\n\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-212da0d elementor-widget elementor-widget-text-editor\" data-id=\"212da0d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a style=\"color: #ffffff00; font-size: 1pt; line-height: 2pt; height: auto; position: absolute;\" href=\"https:\/\/mostbet-bet-uz.com\/\">mostbet<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1e1ad24\" data-id=\"1e1ad24\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a1813d6 elementor-widget__width-auto aux-appear-watch-animation aux-mask-from-left elementor-widget elementor-widget-aux_image\" data-id=\"a1813d6\" data-element_type=\"widget\" data-widget_type=\"aux_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-image aux-alignnone aux-parent-au16a08859\">\n    <div class=\"aux-media-hint-frame \">\n        <div class=\"aux-media-image \" >\n        \n            \n\n            \n            <img loading=\"lazy\" decoding=\"async\" width=\"910\" height=\"666\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/Vector-7.png\" class=\"aux-attachment aux-featured-image aux-attachment-id-75\" alt=\"demo-attachment-307-Vector-7\" data-ratio=\"1.37\" data-original-w=\"910\" \/>            \n                <\/div>\n    <\/div>\n\n<\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"aux-scroll-anim elementor-element elementor-element-0dd2dc9 aux-appear-watch-animation aux-scale-down elementor-widget elementor-widget-aux_image\" data-move-in=\"scale\" data-move-out=\"scale\" data-axis-x=\"200\" data-axis-y=\"200\" data-rotate=\"90\" data-scale=\"0.78\" data-vp-top=\"0.5\" data-vp-bot=\"0.5\" data-el-top=\"0.2\" data-scroll-animation-off=\"1024\" data-id=\"0dd2dc9\" data-element_type=\"widget\" data-widget_type=\"aux_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-image aux-alignnone aux-parent-au18887686\">\n    <div class=\"aux-media-hint-frame \">\n        <div class=\"aux-media-image \" >\n        \n            \n\n            \n            <img loading=\"lazy\" decoding=\"async\" width=\"726\" height=\"674\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/Scroll-Group-1.png\" class=\"aux-attachment aux-featured-image aux-attachment-id-81\" alt=\"demo-attachment-292-Scroll-Group-1\" data-ratio=\"1.08\" data-original-w=\"726\" \/>            \n                <\/div>\n    <\/div>\n\n<\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd2d73f elementor-widget elementor-widget-text-editor\" data-id=\"fd2d73f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<a style=\"color: #ffffff00; font-size: 1pt; line-height: 2pt; height: auto; position: absolute;\" href=\"https:\/\/pin-up-live.com\/\">pinup<\/a>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"aux-scroll-anim elementor-element elementor-element-f6a2aac elementor-widget__width-auto aux-appear-watch-animation aux-fade-in-up elementor-widget elementor-widget-aux_image\" data-move-in=\"scale\" data-move-out=\"scale\" data-axis-x=\"200\" data-axis-y=\"200\" data-rotate=\"90\" data-scale=\"0.9\" data-vp-top=\"0.5\" data-vp-bot=\"0.5\" data-el-top=\"0.2\" data-scroll-animation-off=\"1024\" data-id=\"f6a2aac\" data-element_type=\"widget\" data-widget_type=\"aux_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-image aux-alignnone aux-parent-au19658b69\">\n    <div class=\"aux-media-hint-frame \">\n        <div class=\"aux-media-image \" >\n        \n            \n\n            \n            <img loading=\"lazy\" decoding=\"async\" width=\"1198\" height=\"1198\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/Man-03.png\" class=\"aux-attachment aux-featured-image aux-attachment-id-273\" alt=\"Man-03\" data-ratio=\"1\" data-original-w=\"1198\" \/>            \n                <\/div>\n    <\/div>\n\n<\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45f4b10 elementor-widget__width-auto aux-shpe-type-circle elementor-widget elementor-widget-aux_simple_shape\" data-id=\"45f4b10\" data-element_type=\"widget\" data-widget_type=\"aux_simple_shape.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t    <div class=\"aux-widget-container aux-simple-shape-container\">\n        <div class=\"aux-widget-container-inner\">\n            <div class=\"aux-the-shape\"><\/div>\n        <\/div>\n    <\/div>\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe69378 elementor-widget__width-auto aux-shpe-type-circle elementor-widget elementor-widget-aux_simple_shape\" data-id=\"fe69378\" data-element_type=\"widget\" data-widget_type=\"aux_simple_shape.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t    <div class=\"aux-widget-container aux-simple-shape-container\">\n        <div class=\"aux-widget-container-inner\">\n            <div class=\"aux-the-shape\"><\/div>\n        <\/div>\n    <\/div>\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c8f8c1 elementor-widget__width-auto aux-shpe-type-circle elementor-widget elementor-widget-aux_simple_shape\" data-id=\"7c8f8c1\" data-element_type=\"widget\" data-widget_type=\"aux_simple_shape.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t    <div class=\"aux-widget-container aux-simple-shape-container\">\n        <div class=\"aux-widget-container-inner\">\n            <div class=\"aux-the-shape\"><\/div>\n        <\/div>\n    <\/div>\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0dd7429 elementor-widget__width-auto aux-shpe-type-circle elementor-widget elementor-widget-aux_simple_shape\" data-id=\"0dd7429\" data-element_type=\"widget\" data-widget_type=\"aux_simple_shape.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t    <div class=\"aux-widget-container aux-simple-shape-container\">\n        <div class=\"aux-widget-container-inner\">\n            <div class=\"aux-the-shape\"><\/div>\n        <\/div>\n    <\/div>\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"aux-scroll-anim elementor-element elementor-element-5fcc51e elementor-widget__width-auto aux-appear-watch-animation aux-scale-down elementor-widget elementor-widget-aux_image\" data-move-in=\"moveHorizontal\" data-move-out=\"moveHorizontal\" data-axis-x=\"10\" data-axis-y=\"200\" data-rotate=\"90\" data-scale=\"1\" data-vp-top=\"0.5\" data-vp-bot=\"0.5\" data-el-top=\"0.2\" data-scroll-animation-off=\"1024\" data-id=\"5fcc51e\" data-element_type=\"widget\" data-widget_type=\"aux_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-image aux-alignnone aux-parent-au1b783105\">\n    <div class=\"aux-media-hint-frame \">\n        <div class=\"aux-media-image \" >\n        \n            \n\n            \n            <img loading=\"lazy\" decoding=\"async\" width=\"275\" height=\"330\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/Group-3.png\" class=\"aux-attachment aux-featured-image aux-attachment-id-79\" alt=\"demo-attachment-297-Group-3\" data-ratio=\"0.83\" data-original-w=\"275\" \/>            \n                <\/div>\n    <\/div>\n\n<\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4965e21 elementor-widget__width-auto aux-appear-watch-animation aux-scale-down elementor-widget elementor-widget-aux_image\" data-id=\"4965e21\" data-element_type=\"widget\" data-widget_type=\"aux_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-image aux-alignnone aux-parent-au22dea6db\">\n    <div class=\"aux-media-hint-frame \">\n        <div class=\"aux-media-image \" >\n        \n            \n\n            \n            <img loading=\"lazy\" decoding=\"async\" width=\"114\" height=\"114\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/Group-4.png\" class=\"aux-attachment aux-featured-image aux-attachment-id-78\" alt=\"demo-attachment-301-Group-4\" data-ratio=\"1\" data-original-w=\"114\" \/>            \n                <\/div>\n    <\/div>\n\n<\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"aux-scroll-anim elementor-element elementor-element-defb579 elementor-widget__width-auto elementor-widget elementor-widget-aux_image\" data-move-in=\"moveHorizontal\" data-move-out=\"moveVertical\" data-axis-x=\"200\" data-axis-y=\"70\" data-rotate=\"90\" data-scale=\"1\" data-vp-top=\"0.5\" data-vp-bot=\"0.5\" data-el-top=\"0.2\" data-scroll-animation-off=\"1024\" data-id=\"defb579\" data-element_type=\"widget\" data-widget_type=\"aux_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-image aux-alignnone aux-parent-aud29c5248\">\n    <div class=\"aux-media-hint-frame \">\n        <div class=\"aux-media-image \" >\n        \n            \n\n            \n            <img loading=\"lazy\" decoding=\"async\" width=\"91\" height=\"127\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/Sandwatch-Left.png\" class=\"aux-attachment aux-featured-image aux-attachment-id-76\" alt=\"demo-attachment-306-Sandwatch-Left\" data-ratio=\"0.72\" data-original-w=\"91\" \/>            \n                <\/div>\n    <\/div>\n\n<\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"aux-scroll-anim elementor-element elementor-element-2766a69 elementor-widget__width-auto elementor-widget elementor-widget-aux_image\" data-move-in=\"moveHorizontal\" data-move-out=\"moveHorizontal\" data-axis-x=\"-30\" data-axis-y=\"200\" data-rotate=\"90\" data-scale=\"1\" data-vp-top=\"0.5\" data-vp-bot=\"0.5\" data-el-top=\"0.2\" data-scroll-animation-off=\"1024\" data-id=\"2766a69\" data-element_type=\"widget\" data-widget_type=\"aux_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-image aux-alignnone aux-parent-aufdc8b294\">\n    <div class=\"aux-media-hint-frame \">\n        <div class=\"aux-media-image \" >\n        \n            \n\n            \n            <img loading=\"lazy\" decoding=\"async\" width=\"113\" height=\"89\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/ToggleOn.png\" class=\"aux-attachment aux-featured-image aux-attachment-id-74\" alt=\"demo-attachment-311-ToggleOn\" data-ratio=\"1.27\" data-original-w=\"113\" \/>            \n                <\/div>\n    <\/div>\n\n<\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"aux-scroll-anim elementor-element elementor-element-cf457d8 elementor-widget__width-auto aux-appear-watch-animation aux-scale-down elementor-widget elementor-widget-aux_image\" data-move-in=\"rotateIn\" data-move-out=\"rotateIn\" data-axis-x=\"200\" data-axis-y=\"60\" data-rotate=\"20\" data-scale=\"1\" data-vp-top=\"0.5\" data-vp-bot=\"0.5\" data-el-top=\"0.2\" data-scroll-animation-off=\"1024\" data-id=\"cf457d8\" data-element_type=\"widget\" data-widget_type=\"aux_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-image aux-alignnone aux-parent-au634683a8\">\n    <div class=\"aux-media-hint-frame \">\n        <div class=\"aux-media-image \" >\n        \n            \n\n            \n            <img loading=\"lazy\" decoding=\"async\" width=\"165\" height=\"162\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/Pie-Left.png\" class=\"aux-attachment aux-featured-image aux-attachment-id-77\" alt=\"demo-attachment-305-Pie-Left\" data-ratio=\"1.02\" data-original-w=\"165\" \/>            \n                <\/div>\n    <\/div>\n\n<\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"aux-scroll-anim elementor-element elementor-element-7b244cf elementor-widget__width-auto aux-appear-watch-animation aux-scale-down elementor-widget elementor-widget-aux_image\" data-move-in=\"moveHorizontal\" data-move-out=\"moveHorizontal\" data-axis-x=\"40\" data-axis-y=\"200\" data-rotate=\"90\" data-scale=\"1\" data-vp-top=\"0.5\" data-vp-bot=\"0.5\" data-el-top=\"0.2\" data-scroll-animation-off=\"1024\" data-id=\"7b244cf\" data-element_type=\"widget\" data-widget_type=\"aux_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-image aux-alignnone aux-parent-aua8e31dea\">\n    <div class=\"aux-media-hint-frame \">\n        <div class=\"aux-media-image \" >\n        \n            \n\n            \n            <img loading=\"lazy\" decoding=\"async\" width=\"230\" height=\"112\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/Card-23.png\" class=\"aux-attachment aux-featured-image aux-attachment-id-80\" alt=\"demo-attachment-296-Card-23\" data-ratio=\"2.05\" data-original-w=\"230\" \/>            \n                <\/div>\n    <\/div>\n\n<\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d82c5c1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d82c5c1\" data-element_type=\"section\" id=\"services\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-dfd85ff\" data-id=\"dfd85ff\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fbe9261 aux-appear-watch-animation aux-scale-down elementor-widget elementor-widget-aux_modern_heading\" data-id=\"fbe9261\" data-element_type=\"widget\" data-widget_type=\"aux_modern_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"aux-widget-modern-heading\">\n            <div class=\"aux-widget-inner\"><div class=\"aux-modern-heading-divider\"><\/div><h5 class=\"aux-modern-heading-primary\">Our Services<\/h5><h3 class=\"aux-modern-heading-secondary\"><span class=\"aux-head-highlight\">special features<\/span><\/h3><\/div>\n        <\/section>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-38ccaf2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"38ccaf2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-e1bfce0\" data-id=\"e1bfce0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a0db937 elementor-widget elementor-widget-image\" data-id=\"a0db937\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/tablet_1536103.png\" class=\"attachment-large size-large wp-image-161\" alt=\"\" srcset=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/tablet_1536103.png 512w, https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/tablet_1536103-300x300.png 300w, https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/tablet_1536103-150x150.png 150w, https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/tablet_1536103-200x200.png 200w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26abb3c elementor-widget elementor-widget-heading\" data-id=\"26abb3c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Media Production<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-aeb0163\" data-id=\"aeb0163\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4690d6f elementor-widget elementor-widget-image\" data-id=\"4690d6f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/box_6111281.png\" class=\"attachment-large size-large wp-image-162\" alt=\"\" srcset=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/box_6111281.png 512w, https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/box_6111281-300x300.png 300w, https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/box_6111281-150x150.png 150w, https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/box_6111281-200x200.png 200w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4618af5 elementor-widget elementor-widget-heading\" data-id=\"4618af5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Digital Marketing<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-935c941\" data-id=\"935c941\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8ec1604 elementor-widget elementor-widget-image\" data-id=\"8ec1604\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/social-media_8163935.png\" class=\"attachment-large size-large wp-image-163\" alt=\"\" srcset=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/social-media_8163935.png 512w, https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/social-media_8163935-300x300.png 300w, https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/social-media_8163935-150x150.png 150w, https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/social-media_8163935-200x200.png 200w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f8227dc elementor-widget elementor-widget-heading\" data-id=\"f8227dc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Social Media Management <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-f40faaa\" data-id=\"f40faaa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c55d55e elementor-widget elementor-widget-image\" data-id=\"c55d55e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/ad_9734000.png\" class=\"attachment-large size-large wp-image-165\" alt=\"\" srcset=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/ad_9734000.png 512w, https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/ad_9734000-300x300.png 300w, https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/ad_9734000-150x150.png 150w, https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/ad_9734000-200x200.png 200w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a17b7e8 elementor-widget elementor-widget-heading\" data-id=\"a17b7e8\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Social Media Ads<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-ffbdc07\" data-id=\"ffbdc07\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1fadbdb elementor-widget elementor-widget-image\" data-id=\"1fadbdb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/market-research_9011673.png\" class=\"attachment-large size-large wp-image-166\" alt=\"\" srcset=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/market-research_9011673.png 512w, https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/market-research_9011673-300x300.png 300w, https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/market-research_9011673-150x150.png 150w, https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/market-research_9011673-200x200.png 200w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-03b4c9c elementor-widget elementor-widget-heading\" data-id=\"03b4c9c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Market Research & Analysis<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-120b1cd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"120b1cd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-ecba349\" data-id=\"ecba349\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11803bd elementor-widget elementor-widget-image\" data-id=\"11803bd\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/brand_9899411.png\" class=\"attachment-large size-large wp-image-167\" alt=\"\" srcset=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/brand_9899411.png 512w, https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/brand_9899411-300x300.png 300w, https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/brand_9899411-150x150.png 150w, https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/brand_9899411-200x200.png 200w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-355e6d9 elementor-widget elementor-widget-heading\" data-id=\"355e6d9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Branding<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-28b5f21\" data-id=\"28b5f21\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-434bd8b elementor-widget elementor-widget-image\" data-id=\"434bd8b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/seo_2977790.png\" class=\"attachment-large size-large wp-image-168\" alt=\"\" srcset=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/seo_2977790.png 512w, https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/seo_2977790-300x300.png 300w, https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/seo_2977790-150x150.png 150w, https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/seo_2977790-200x200.png 200w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f303c93 elementor-widget elementor-widget-heading\" data-id=\"f303c93\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SEO<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-ba1d0a1\" data-id=\"ba1d0a1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4311b21 elementor-widget elementor-widget-image\" data-id=\"4311b21\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/search_8416276.png\" class=\"attachment-large size-large wp-image-169\" alt=\"\" srcset=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/search_8416276.png 512w, https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/search_8416276-300x300.png 300w, https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/search_8416276-150x150.png 150w, https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/search_8416276-200x200.png 200w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5922014 elementor-widget elementor-widget-heading\" data-id=\"5922014\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">SEM<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-7a37f8c\" data-id=\"7a37f8c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8654914 elementor-widget elementor-widget-image\" data-id=\"8654914\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/design_9451638.png\" class=\"attachment-large size-large wp-image-170\" alt=\"\" srcset=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/design_9451638.png 512w, https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/design_9451638-300x300.png 300w, https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/design_9451638-150x150.png 150w, https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/design_9451638-200x200.png 200w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95aa9cd elementor-widget elementor-widget-heading\" data-id=\"95aa9cd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Copywriting<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-20 elementor-inner-column elementor-element elementor-element-7da3e86\" data-id=\"7da3e86\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8af8a78 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8af8a78\" data-element_type=\"section\" id=\"about\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5aaacf2\" data-id=\"5aaacf2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9762d3f elementor-widget elementor-widget-aux_image\" data-id=\"9762d3f\" data-element_type=\"widget\" data-widget_type=\"aux_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-image aux-alignnone aux-parent-au38493b18\">\n    <div class=\"aux-media-hint-frame \">\n        <div class=\"aux-media-image \" >\n        \n            \n\n            \n            <img loading=\"lazy\" decoding=\"async\" width=\"769\" height=\"769\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/Ellipse-8.png\" class=\"aux-attachment aux-featured-image aux-attachment-id-66\" alt=\"demo-attachment-562-Ellipse-8\" data-ratio=\"1\" data-original-w=\"769\" \/>            \n                <\/div>\n    <\/div>\n\n<\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21f6376 elementor-widget__width-auto aux-shpe-type-circle elementor-widget elementor-widget-aux_simple_shape\" data-id=\"21f6376\" data-element_type=\"widget\" data-widget_type=\"aux_simple_shape.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t    <div class=\"aux-widget-container aux-simple-shape-container\">\n        <div class=\"aux-widget-container-inner\">\n            <div class=\"aux-the-shape\"><\/div>\n        <\/div>\n    <\/div>\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81a2a59 elementor-widget__width-auto elementor-widget elementor-widget-aux_image\" data-id=\"81a2a59\" data-element_type=\"widget\" data-widget_type=\"aux_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-image aux-alignnone aux-parent-au86c8f6ae\">\n    <div class=\"aux-media-hint-frame \">\n        <div class=\"aux-media-image \" >\n        \n            \n\n            \n            <img loading=\"lazy\" decoding=\"async\" width=\"796\" height=\"855\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/Phone-Front.png\" class=\"aux-attachment aux-featured-image aux-attachment-id-64\" alt=\"demo-attachment-564-Phone-Front\" data-ratio=\"0.93\" data-original-w=\"796\" \/>            \n                <\/div>\n    <\/div>\n\n<\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c585c5e elementor-widget__width-auto aux-shpe-type-circle elementor-widget elementor-widget-aux_simple_shape\" data-id=\"c585c5e\" data-element_type=\"widget\" data-widget_type=\"aux_simple_shape.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t    <div class=\"aux-widget-container aux-simple-shape-container\">\n        <div class=\"aux-widget-container-inner\">\n            <div class=\"aux-the-shape\"><\/div>\n        <\/div>\n    <\/div>\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5fbb9ea elementor-widget__width-auto aux-shpe-type-circle elementor-widget elementor-widget-aux_simple_shape\" data-id=\"5fbb9ea\" data-element_type=\"widget\" data-widget_type=\"aux_simple_shape.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t    <div class=\"aux-widget-container aux-simple-shape-container\">\n        <div class=\"aux-widget-container-inner\">\n            <div class=\"aux-the-shape\"><\/div>\n        <\/div>\n    <\/div>\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"aux-scroll-anim elementor-element elementor-element-58ac0c9 elementor-widget__width-auto elementor-widget elementor-widget-aux_image\" data-move-in=\"moveHorizontal\" data-move-out=\"moveHorizontal\" data-axis-x=\"-20\" data-axis-y=\"200\" data-rotate=\"90\" data-scale=\"1\" data-vp-top=\"0.5\" data-vp-bot=\"0.5\" data-el-top=\"0.2\" data-scroll-animation-off=\"1024\" data-id=\"58ac0c9\" data-element_type=\"widget\" data-widget_type=\"aux_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-image aux-alignnone aux-parent-audbc68edc\">\n    <div class=\"aux-media-hint-frame \">\n        <div class=\"aux-media-image \" >\n        \n            \n\n            \n            <img loading=\"lazy\" decoding=\"async\" width=\"390\" height=\"571\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/Card-11.png\" class=\"aux-attachment aux-featured-image aux-attachment-id-68\" alt=\"demo-attachment-560-Card-11\" data-ratio=\"0.68\" data-original-w=\"390\" \/>            \n                <\/div>\n    <\/div>\n\n<\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-add0166 elementor-widget__width-auto elementor-widget elementor-widget-aux_image\" data-id=\"add0166\" data-element_type=\"widget\" data-widget_type=\"aux_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-image aux-alignnone aux-parent-au550afac0\">\n    <div class=\"aux-media-hint-frame \">\n        <div class=\"aux-media-image \" >\n        \n            \n\n            \n            <img loading=\"lazy\" decoding=\"async\" width=\"202\" height=\"202\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/Ellipse-7.png\" class=\"aux-attachment aux-featured-image aux-attachment-id-63\" alt=\"demo-attachment-571-Ellipse-7\" data-ratio=\"1\" data-original-w=\"202\" \/>            \n                <\/div>\n    <\/div>\n\n<\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"aux-scroll-anim elementor-element elementor-element-2b86d45 elementor-widget__width-auto elementor-widget elementor-widget-aux_image\" data-move-in=\"rotateIn\" data-move-out=\"rotateIn\" data-axis-x=\"200\" data-axis-y=\"200\" data-rotate=\"10\" data-scale=\"1\" data-vp-top=\"0.5\" data-vp-bot=\"0.5\" data-el-top=\"0.2\" data-scroll-animation-off=\"1024\" data-id=\"2b86d45\" data-element_type=\"widget\" data-widget_type=\"aux_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-image aux-alignnone aux-parent-au8b86fe63\">\n    <div class=\"aux-media-hint-frame \">\n        <div class=\"aux-media-image \" >\n        \n            \n\n            \n            <img loading=\"lazy\" decoding=\"async\" width=\"415\" height=\"353\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/Card-Left.png\" class=\"aux-attachment aux-featured-image aux-attachment-id-67\" alt=\"demo-attachment-561-Card-Left\" data-ratio=\"1.18\" data-original-w=\"415\" \/>            \n                <\/div>\n    <\/div>\n\n<\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"aux-scroll-anim elementor-element elementor-element-6ee0a5a elementor-widget__width-auto elementor-widget elementor-widget-aux_image\" data-move-in=\"moveVertical\" data-move-out=\"moveVertical\" data-axis-x=\"200\" data-axis-y=\"20\" data-rotate=\"90\" data-scale=\"1\" data-vp-top=\"0.5\" data-vp-bot=\"0.5\" data-el-top=\"0.2\" data-scroll-animation-off=\"1024\" data-id=\"6ee0a5a\" data-element_type=\"widget\" data-widget_type=\"aux_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-image aux-alignnone aux-parent-au82db6988\">\n    <div class=\"aux-media-hint-frame \">\n        <div class=\"aux-media-image \" >\n        \n            \n\n            \n            <img loading=\"lazy\" decoding=\"async\" width=\"311\" height=\"392\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/Bell-Right.png\" class=\"aux-attachment aux-featured-image aux-attachment-id-69\" alt=\"demo-attachment-559-Bell-Right\" data-ratio=\"0.79\" data-original-w=\"311\" \/>            \n                <\/div>\n    <\/div>\n\n<\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"aux-scroll-anim elementor-element elementor-element-387cbb5 elementor-widget__width-auto elementor-widget elementor-widget-aux_image\" data-move-in=\"moveHorizontal\" data-move-out=\"moveHorizontal\" data-axis-x=\"25\" data-axis-y=\"200\" data-rotate=\"90\" data-scale=\"1\" data-vp-top=\"0.5\" data-vp-bot=\"0.5\" data-el-top=\"0.2\" data-scroll-animation-off=\"1024\" data-id=\"387cbb5\" data-element_type=\"widget\" data-widget_type=\"aux_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-image aux-alignnone aux-parent-auf15f051c\">\n    <div class=\"aux-media-hint-frame \">\n        <div class=\"aux-media-image \" >\n        \n            \n\n            \n            <img loading=\"lazy\" decoding=\"async\" width=\"697\" height=\"980\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/Man-01.png\" class=\"aux-attachment aux-featured-image aux-attachment-id-277\" alt=\"Man-01\" data-ratio=\"0.71\" data-original-w=\"697\" \/>            \n                <\/div>\n    <\/div>\n\n<\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e69f499 elementor-widget__width-auto elementor-widget elementor-widget-aux_image\" data-id=\"e69f499\" data-element_type=\"widget\" data-widget_type=\"aux_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-image aux-alignnone aux-parent-auf1604436\">\n    <div class=\"aux-media-hint-frame \">\n        <div class=\"aux-media-image \" >\n        \n            \n\n            \n            <img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"565\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/07\/Logo-Aura.png\" class=\"aux-attachment aux-featured-image aux-attachment-id-136\" alt=\"Logo Aura\" data-ratio=\"0.88\" data-original-w=\"500\" \/>            \n                <\/div>\n    <\/div>\n\n<\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dce082b elementor-widget__width-auto aux-shpe-type-circle elementor-widget elementor-widget-aux_simple_shape\" data-id=\"dce082b\" data-element_type=\"widget\" data-widget_type=\"aux_simple_shape.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t    <div class=\"aux-widget-container aux-simple-shape-container\">\n        <div class=\"aux-widget-container-inner\">\n            <div class=\"aux-the-shape\"><\/div>\n        <\/div>\n    <\/div>\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0385674\" data-id=\"0385674\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6f0ea2e aux-appear-watch-animation aux-fade-in-up-1 elementor-widget elementor-widget-aux_modern_heading\" data-id=\"6f0ea2e\" data-element_type=\"widget\" data-widget_type=\"aux_modern_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"aux-widget-modern-heading\">\n            <div class=\"aux-widget-inner\"><h5 class=\"aux-modern-heading-primary\">company's vision<\/h5><h2 class=\"aux-modern-heading-secondary\"><span class=\"aux-head-highlight\">Being One Of The Most Important Companies <\/span><\/h2><div class=\"aux-modern-heading-description\">Provide the  best customer results and deliver wow factor through our services .\n<div style=\"overflow:hidden;height:1px\"><a href=\"https:\/\/sardicafelounge.com\/\">Ba\u015far\u0131bet<\/a><\/div>\n<\/div><\/div>\n        <\/section>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4bc09d elementor-widget__width-auto aux-appear-watch-animation aux-fade-in-right elementor-widget elementor-widget-aux_modern_button\" data-id=\"d4bc09d\" data-element_type=\"widget\" data-widget_type=\"aux_modern_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t    <div class=\"aux-modern-button-wrapper aux-modern-button-align-left\" >\n                    <a class=\"aux-modern-button aux-black aux-modern-button-md aux-modern-button-normal aux-modern-button-default aux-icon-\" href=\"tel:+201011332871\">\n                <div class=\"aux-overlay\"><\/div>\n                                    <div class=\"aux-icon \">\n                                            <\/div>\n                                <div class=\"aux-text\">\n<span class=\"aux-text-before\">contact us<\/span>                <\/div>\n            <\/a>\n            \n    <\/div>\n\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d20e1c elementor-section-full_width elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"6d20e1c\" data-element_type=\"section\" id=\"projects\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ab8bc95\" data-id=\"ab8bc95\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"aux-scroll-anim elementor-element elementor-element-63aa071 elementor-widget__width-auto elementor-widget elementor-widget-aux_image\" data-move-in=\"moveVertical\" data-move-out=\"moveVertical\" data-axis-x=\"200\" data-axis-y=\"40\" data-rotate=\"90\" data-scale=\"1\" data-vp-top=\"0.5\" data-vp-bot=\"0.5\" data-el-top=\"0.2\" data-scroll-animation-off=\"1024\" data-id=\"63aa071\" data-element_type=\"widget\" data-widget_type=\"aux_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-image aux-alignnone aux-parent-au0bd418f0\">\n    <div class=\"aux-media-hint-frame \">\n        <div class=\"aux-media-image \" >\n        \n            \n\n            \n            <img loading=\"lazy\" decoding=\"async\" width=\"358\" height=\"358\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/Rocket-Right.png\" class=\"aux-attachment aux-featured-image aux-attachment-id-57\" alt=\"demo-attachment-799-Rocket-Right\" data-ratio=\"1\" data-original-w=\"358\" \/>            \n                <\/div>\n    <\/div>\n\n<\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"aux-scroll-anim elementor-element elementor-element-f67f3bb elementor-widget__width-auto elementor-widget elementor-widget-aux_image\" data-move-in=\"moveHorizontal\" data-move-out=\"moveHorizontal\" data-axis-x=\"20\" data-axis-y=\"200\" data-rotate=\"90\" data-scale=\"1\" data-vp-top=\"0.5\" data-vp-bot=\"0.5\" data-el-top=\"0.2\" data-scroll-animation-off=\"1024\" data-id=\"f67f3bb\" data-element_type=\"widget\" data-widget_type=\"aux_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-image aux-alignnone aux-parent-aubbd41a9d\">\n    <div class=\"aux-media-hint-frame \">\n        <div class=\"aux-media-image \" >\n        \n            \n\n            \n            <img loading=\"lazy\" decoding=\"async\" width=\"348\" height=\"437\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/Hand-01-L.png\" class=\"aux-attachment aux-featured-image aux-attachment-id-56\" alt=\"demo-attachment-803-Hand-01-L\" data-ratio=\"0.8\" data-original-w=\"348\" \/>            \n                <\/div>\n    <\/div>\n\n<\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-db7ef5b elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"db7ef5b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-82fa0bf\" data-id=\"82fa0bf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9902a32 elementor-widget__width-auto aux-appear-watch-animation aux-fade-in-up-1 elementor-widget elementor-widget-aux_modern_heading\" data-id=\"9902a32\" data-element_type=\"widget\" data-widget_type=\"aux_modern_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"aux-widget-modern-heading\">\n            <div class=\"aux-widget-inner\"><h5 class=\"aux-modern-heading-primary\">Selected project<\/h5><h3 class=\"aux-modern-heading-secondary\"><span class=\"aux-head-highlight\">Digital Case Studies<\/span><\/h3><\/div>\n        <\/section>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee6f582 elementor-widget__width-auto aux-appear-watch-animation aux-fade-in-right elementor-widget elementor-widget-aux_modern_button\" data-id=\"ee6f582\" data-element_type=\"widget\" data-widget_type=\"aux_modern_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t    <div class=\"aux-modern-button-wrapper aux-modern-button-align-left\" >\n                    <a class=\"aux-modern-button aux-black aux-modern-button-md aux-modern-button-normal aux-modern-button-default aux-icon-\" href=\"#\">\n                <div class=\"aux-overlay\"><\/div>\n                                    <div class=\"aux-icon \">\n                                            <\/div>\n                                <div class=\"aux-text\">\n<span class=\"aux-text-before\">See more works<\/span>                <\/div>\n            <\/a>\n            \n    <\/div>\n\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27c0dd5 aux-appear-watch-animation aux-scale-down elementor-widget elementor-widget-aux_recent_portfolios_grid\" data-id=\"27c0dd5\" data-element_type=\"widget\" data-settings=\"{&quot;columns&quot;:&quot;3&quot;,&quot;columns_tablet&quot;:&quot;3&quot;,&quot;columns_mobile&quot;:&quot;1&quot;}\" data-widget_type=\"aux_recent_portfolios_grid.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-recent-portfolios aux-parent-au7e2ebd02\" style=\"\" ><div id=\"6a57ef17a9e22\" data-element-id=\"au7e2ebd02\" class=\"aux-portfolio-columns aux-ajax-view aux-isotope-animated aux-isotope-layout aux-layout-grid aux-no-gutter aux-row aux-match-height aux-de-col3 aux-tb-col3 aux-mb-col1\" data-lazyload=\"true\" data-space=\"30\" data-pagination=\"true\" data-deeplink=\"true\" data-slug=\"\" data-perpage=\"8\" data-layout=\"fitRows\" data-reveal-transition-duration=\"600\" data-reveal-between-delay=\"60\" data-hide-transition-duration=\"600\" data-hide-between-delay=\"30\" data-num=\"3\" data-order=\"ASC\" data-orderby=\"date\" data-taxonomy=\"\" data-n=\"f35d5c4700\"><div class=\"aux-items-loading aux-loading-hide\"><div class=\"aux-loading-loop\"><svg class=\"aux-circle\" width=\"100%\" height=\"100%\" viewBox=\"0 0 42 42\"><circle class=\"aux-stroke-bg\" r=\"20\" cx=\"21\" cy=\"21\" fill=\"none\"><\/circle><circle class=\"aux-progress\" r=\"20\" cx=\"21\" cy=\"21\" fill=\"none\" transform=\"rotate(-90 21 21)\"><\/circle><\/svg><\/div><\/div><div class=\"aux-iso-item aux-loading aux-col\">                        <article class=\"post-112 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-branding-identity portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                            <div class=\"\">\n                                <div class=\"entry-media \">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/aura-agency-eg.com\/index.php\/portfolio\/the-portrait\/\"><img width=\"606\" height=\"633\" class=\"aux-attachment aux-featured-image attachment-606.66666666667x633.96666666667 aux-attachment-id-60 \" alt=\"demo-attachment-788-qoc8cl04\" data-ratio=\"0.96\" data-original-w=\"1200\" sizes=\"auto\" data-srcset=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/qoc8cl04-150x157.png 150w,https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/qoc8cl04-300x314.png 300w,https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/qoc8cl04-768x803.png 768w,https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/qoc8cl04-1024x1070.png 1024w,https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/qoc8cl04.png 607w,https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/qoc8cl04-1190x1243.png 1190w\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/qoc8cl04.png\" \/><\/a><\/div>                                <\/div>\n\n                                                            <\/div>\n\n                                                        <div class=\"entry-main\">\n\n                                                                <header class=\"entry-header\">\n                                    <h3 class=\"entry-title\">\n                                        <a href=\"https:\/\/aura-agency-eg.com\/index.php\/portfolio\/the-portrait\/\">\n                                            the portrait                                        <\/a>\n                                    <\/h3>\n                                <\/header>\n                                                                \t\t<div class=\"wpulike wpulike-heart aux-wpulike aux-wpulike-portfolio-widget\" ><div class=\"wp_ulike_general_class wp_ulike_is_not_liked\"><button type=\"button\"\n\t\t\t\t\taria-label=\"Like Button\"\n\t\t\t\t\tdata-ulike-id=\"112\"\n\t\t\t\t\tdata-ulike-nonce=\"c1e25a6c26\"\n\t\t\t\t\tdata-ulike-type=\"post\"\n\t\t\t\t\tdata-ulike-template=\"wpulike-heart\"\n\t\t\t\t\tdata-ulike-display-likers=\"0\"\n\t\t\t\t\tdata-ulike-likers-style=\"popover\"\n\t\t\t\t\tclass=\"wp_ulike_btn wp_ulike_put_image wp_post_btn_112\"><\/button><span class=\"count-box wp_ulike_counter_up\" data-ulike-counter-value=\"0\"><\/span>\t\t\t<\/div><\/div>\n\t                                                                <div class=\"entry-info\">\n                                    <span class=\"entry-tax\">\n                                                                                <a href=\"https:\/\/aura-agency-eg.com\/index.php\/portfolio-cat\/branding-identity\/\" title=\"View all posts in branding identity\" rel=\"category\" >branding identity<\/a>                                    <\/span>\n                                <\/div>\n                                                                                            <\/div>\n                            \n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-col\">                        <article class=\"post-111 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-custom-print portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                            <div class=\"\">\n                                <div class=\"entry-media \">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/aura-agency-eg.com\/index.php\/portfolio\/artboard-studio\/\"><img width=\"606\" height=\"633\" class=\"aux-attachment aux-featured-image attachment-606.66666666667x633.96666666667 aux-attachment-id-59 \" alt=\"demo-attachment-789-rc5vcgxp\" data-ratio=\"0.96\" data-original-w=\"1200\" sizes=\"auto\" data-srcset=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/rc5vcgxp-150x157.png 150w,https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/rc5vcgxp-300x314.png 300w,https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/rc5vcgxp-768x803.png 768w,https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/rc5vcgxp-1024x1070.png 1024w,https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/rc5vcgxp.png 607w,https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/rc5vcgxp-1190x1243.png 1190w\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/rc5vcgxp.png\" \/><\/a><\/div>                                <\/div>\n\n                                                            <\/div>\n\n                                                        <div class=\"entry-main\">\n\n                                                                <header class=\"entry-header\">\n                                    <h3 class=\"entry-title\">\n                                        <a href=\"https:\/\/aura-agency-eg.com\/index.php\/portfolio\/artboard-studio\/\">\n                                            artboard studio                                        <\/a>\n                                    <\/h3>\n                                <\/header>\n                                                                \t\t<div class=\"wpulike wpulike-heart aux-wpulike aux-wpulike-portfolio-widget\" ><div class=\"wp_ulike_general_class wp_ulike_is_not_liked\"><button type=\"button\"\n\t\t\t\t\taria-label=\"Like Button\"\n\t\t\t\t\tdata-ulike-id=\"111\"\n\t\t\t\t\tdata-ulike-nonce=\"3dd5e87a18\"\n\t\t\t\t\tdata-ulike-type=\"post\"\n\t\t\t\t\tdata-ulike-template=\"wpulike-heart\"\n\t\t\t\t\tdata-ulike-display-likers=\"0\"\n\t\t\t\t\tdata-ulike-likers-style=\"popover\"\n\t\t\t\t\tclass=\"wp_ulike_btn wp_ulike_put_image wp_post_btn_111\"><\/button><span class=\"count-box wp_ulike_counter_up\" data-ulike-counter-value=\"0\"><\/span>\t\t\t<\/div><\/div>\n\t                                                                <div class=\"entry-info\">\n                                    <span class=\"entry-tax\">\n                                                                                <a href=\"https:\/\/aura-agency-eg.com\/index.php\/portfolio-cat\/custom-print\/\" title=\"View all posts in custom print\" rel=\"category\" >custom print<\/a>                                    <\/span>\n                                <\/div>\n                                                                                            <\/div>\n                            \n                        <\/article>\n<\/div><div class=\"aux-iso-item aux-loading aux-col\">                        <article class=\"post-110 portfolio type-portfolio status-publish has-post-thumbnail hentry portfolio-cat-branding portfolio-tag-uncategorized portfolio-filter-uncategorized\" >\n                            <div class=\"\">\n                                <div class=\"entry-media \">\n                                    <div class=\"aux-media-frame aux-media-image\"><a href=\"https:\/\/aura-agency-eg.com\/index.php\/portfolio\/nice-shopping\/\"><img width=\"606\" height=\"633\" class=\"aux-attachment aux-featured-image attachment-606.66666666667x633.96666666667 aux-attachment-id-61 \" alt=\"demo-attachment-787-1yjw2r41\" data-ratio=\"0.96\" data-original-w=\"1200\" sizes=\"auto\" data-srcset=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/1yjw2r41-150x157.png 150w,https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/1yjw2r41-300x314.png 300w,https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/1yjw2r41-768x803.png 768w,https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/1yjw2r41-1024x1070.png 1024w,https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/1yjw2r41.png 607w,https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/1yjw2r41-1190x1243.png 1190w\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/1yjw2r41.png\" \/><\/a><\/div>                                <\/div>\n\n                                                            <\/div>\n\n                                                        <div class=\"entry-main\">\n\n                                                                <header class=\"entry-header\">\n                                    <h3 class=\"entry-title\">\n                                        <a href=\"https:\/\/aura-agency-eg.com\/index.php\/portfolio\/nice-shopping\/\">\n                                            nice shopping                                        <\/a>\n                                    <\/h3>\n                                <\/header>\n                                                                \t\t<div class=\"wpulike wpulike-heart aux-wpulike aux-wpulike-portfolio-widget\" ><div class=\"wp_ulike_general_class wp_ulike_is_not_liked\"><button type=\"button\"\n\t\t\t\t\taria-label=\"Like Button\"\n\t\t\t\t\tdata-ulike-id=\"110\"\n\t\t\t\t\tdata-ulike-nonce=\"cfb652a674\"\n\t\t\t\t\tdata-ulike-type=\"post\"\n\t\t\t\t\tdata-ulike-template=\"wpulike-heart\"\n\t\t\t\t\tdata-ulike-display-likers=\"0\"\n\t\t\t\t\tdata-ulike-likers-style=\"popover\"\n\t\t\t\t\tclass=\"wp_ulike_btn wp_ulike_put_image wp_post_btn_110\"><\/button><span class=\"count-box wp_ulike_counter_up\" data-ulike-counter-value=\"0\"><\/span>\t\t\t<\/div><\/div>\n\t                                                                <div class=\"entry-info\">\n                                    <span class=\"entry-tax\">\n                                                                                <a href=\"https:\/\/aura-agency-eg.com\/index.php\/portfolio-cat\/branding\/\" title=\"View all posts in branding\" rel=\"category\" >branding<\/a>                                    <\/span>\n                                <\/div>\n                                                                                            <\/div>\n                            \n                        <\/article>\n<\/div><\/div><script type=\"text\/javascript\">var au7e2ebd02AjaxConfig = {\"title\":\"\",\"cat\":[],\"num\":\"3\",\"only_posts__in\":\"\",\"include\":\"\",\"exclude\":\"\",\"posts_per_page\":-1,\"offset\":\"\",\"order_by\":\"date\",\"order\":\"ASC\",\"exclude_without_media\":\"yes\",\"display_like\":\"no\",\"deeplink\":\"no\",\"use_ajax\":\"no\",\"deeplink_slug\":null,\"show_filters\":\"\",\"filter_by\":null,\"filter_style\":null,\"filter_align\":null,\"reveal_transition_duration\":\"600\",\"reveal_between_delay\":\"60\",\"hide_transition_duration\":\"600\",\"hide_between_delay\":\"30\",\"item_style\":\"classic\",\"tile_style_pattern\":\"default\",\"tiles_item_style\":\"overlay\",\"entry_background_color\":\"\",\"entry_border_color\":\"\",\"paginate\":\"yes\",\"perpage\":\"8\",\"crop\":true,\"display_title\":\"yes\",\"show_info\":\"yes\",\"display_read_more\":false,\"image_aspect_ratio\":\"1.045\",\"space\":\"30\",\"desktop_cnum\":\"3\",\"tablet_cnum\":\"3\",\"phone_cnum\":\"1\",\"layout\":\"grid\",\"tag\":\"\",\"filter\":\"\",\"extra_classes\":\"\",\"extra_column_classes\":\"\",\"custom_el_id\":\"\",\"template_part_file\":\"recent-portfolio\",\"extra_template_path\":\"\\\/home\\\/u798587846\\\/domains\\\/aura-agency-eg.com\\\/public_html\\\/wp-content\\\/plugins\\\/auxin-portfolio\\\/public\\\/templates\\\/elements\",\"universal_id\":\"au7e2ebd02\",\"query_args\":[],\"term\":\"\",\"reset_query\":true,\"use_wp_query\":false,\"wp_query_args\":[],\"custom_wp_query\":\"\",\"loadmore_type\":null,\"loadmore_label\":null,\"loadmore_per_page\":\"3\",\"term_field\":\"slug\",\"base\":\"aux_recent_portfolios_grid\",\"base_class\":\"aux-widget-recent-portfolios\",\"paged\":\"\",\"override_global_query\":false,\"content\":null,\"skip_wrappers\":false,\"content_width\":2000,\"inview_transition\":\"none\",\"inview_duration\":\"\",\"inview_delay\":\"\",\"inview_repeat\":\"no\",\"inview_offset\":\"\",\"called_from\":\"elementor\"};<\/script><\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"aux-scroll-anim elementor-element elementor-element-b314f8d elementor-widget__width-auto elementor-widget elementor-widget-aux_image\" data-move-in=\"rotateOut\" data-move-out=\"rotateOut\" data-axis-x=\"200\" data-axis-y=\"200\" data-rotate=\"90\" data-scale=\"15\" data-vp-top=\"0.5\" data-vp-bot=\"0.5\" data-el-top=\"0.2\" data-scroll-animation-off=\"1024\" data-id=\"b314f8d\" data-element_type=\"widget\" data-widget_type=\"aux_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-image aux-alignnone aux-parent-auc44acee1\">\n    <div class=\"aux-media-hint-frame \">\n        <div class=\"aux-media-image \" >\n        \n            \n\n            \n            <img loading=\"lazy\" decoding=\"async\" width=\"142\" height=\"163\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/Cristall-Right.png\" class=\"aux-attachment aux-featured-image aux-attachment-id-58\" alt=\"demo-attachment-798-Cristall-Right\" data-ratio=\"0.87\" data-original-w=\"142\" \/>            \n                <\/div>\n    <\/div>\n\n<\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1c56aee elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c56aee\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c6ca80e\" data-id=\"c6ca80e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b3b5dfd aux-appear-watch-animation aux-fade-in-up-1 elementor-widget elementor-widget-aux_modern_heading\" data-id=\"b3b5dfd\" data-element_type=\"widget\" data-widget_type=\"aux_modern_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"aux-widget-modern-heading\">\n            <div class=\"aux-widget-inner\"><h5 class=\"aux-modern-heading-primary\">company's Mission<\/h5><h2 class=\"aux-modern-heading-secondary\"><span class=\"aux-head-highlight\">Explore <br> Aura Mission<\/span><\/h2><\/div>\n        <\/section>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"aux-scroll-anim elementor-element elementor-element-6f17926 elementor-widget__width-auto elementor-widget elementor-widget-aux_image\" data-move-in=\"moveHorizontal\" data-move-out=\"moveHorizontal\" data-axis-x=\"20\" data-axis-y=\"200\" data-rotate=\"90\" data-scale=\"1\" data-vp-top=\"0.5\" data-vp-bot=\"0.5\" data-el-top=\"0.2\" data-scroll-animation-off=\"1024\" data-id=\"6f17926\" data-element_type=\"widget\" data-widget_type=\"aux_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-image aux-alignnone aux-parent-au3d9c1df8\">\n    <div class=\"aux-media-hint-frame \">\n        <div class=\"aux-media-image \" >\n        \n            \n\n            \n            <img loading=\"lazy\" decoding=\"async\" width=\"348\" height=\"437\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/Hand-01-L.png\" class=\"aux-attachment aux-featured-image aux-attachment-id-56\" alt=\"demo-attachment-803-Hand-01-L\" data-ratio=\"0.8\" data-original-w=\"348\" \/>            \n                <\/div>\n    <\/div>\n\n<\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b49209 elementor-widget__width-auto aux-appear-watch-animation aux-fade-in-up-1 elementor-widget elementor-widget-aux_icon_list\" data-id=\"0b49209\" data-element_type=\"widget\" data-widget_type=\"aux_icon_list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-icon-list aux-parent-au5031624c\" style=\"\" ><div class=\"widget-inner\"><div class=\"aux-widget-icon-list-inner\"><ul class=\"aux-icon-list-items aux-direction-default\" ><li class=\"aux-icon-list-item aux-list-item-has-icon aux-icon-list-item-3fb25af elementor-repeater-item-3fb25af\" ><span class=\"aux-icon-list-text\" >01<\/span><span class=\"aux-icon-list-text2\" >Develop a comprehensive digital marketing strategy for clients, taking into account their specific goals, target audience, and industry trends.<\/span><\/li><li class=\"aux-icon-list-item aux-list-item-has-icon aux-icon-list-item-1699534 elementor-repeater-item-1699534\" ><span class=\"aux-icon-list-text\" >02<\/span><span class=\"aux-icon-list-text2\" >Conduct in-depth market research and competitor analysis to identify opportunities and create effective marketing campaigns.<\/span><\/li><li class=\"aux-icon-list-item aux-list-item-has-icon aux-icon-list-item-d81ef27 elementor-repeater-item-d81ef27\" ><span class=\"aux-icon-list-text\" >03<\/span><span class=\"aux-icon-list-text2\" >Create and manage engaging social media campaigns across various platforms to increase brand awareness, drive website traffic, and generate leads.<\/span><\/li><li class=\"aux-icon-list-item aux-list-item-has-icon aux-icon-list-item-bb42300 elementor-repeater-item-bb42300\" ><span class=\"aux-icon-list-text\" >04<\/span><span class=\"aux-icon-list-text2\" >Optimize clients' websites for search engines (SEO) to improve organic rankings and increase visibility in search results.<\/span><\/li><li class=\"aux-icon-list-item aux-list-item-has-icon aux-icon-list-item-69662e4 elementor-repeater-item-69662e4\" ><span class=\"aux-icon-list-text\" >05<\/span><span class=\"aux-icon-list-text2\" >Execute paid advertising campaigns on platforms like Google Ads, Facebook ads, and Instagram ads to drive targeted traffic and conversions.<\/span><\/li><li class=\"aux-icon-list-item aux-list-item-has-icon aux-icon-list-item-3cd2794 elementor-repeater-item-3cd2794\" ><span class=\"aux-icon-list-text\" >06<\/span><span class=\"aux-icon-list-text2\" >Monitor and analyze key performance indicators (KPIs) to measure the success of marketing efforts and make data-driven decisions for optimization.<\/span><\/li><li class=\"aux-icon-list-item aux-list-item-has-icon aux-icon-list-item-0dd905f elementor-repeater-item-0dd905f\" ><span class=\"aux-icon-list-text\" >07<\/span><span class=\"aux-icon-list-text2\" >Monitor and analyze key performance indicators (KPIs) to measure the success of marketing efforts and make data-driven decisions for optimization.<\/span><\/li><\/ul><\/div><\/div><\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"aux-scroll-anim elementor-element elementor-element-b225c1f elementor-widget__width-auto elementor-widget elementor-widget-aux_image\" data-move-in=\"rotateIn\" data-move-out=\"rotateIn\" data-axis-x=\"200\" data-axis-y=\"200\" data-rotate=\"12\" data-scale=\"1\" data-vp-top=\"0.5\" data-vp-bot=\"0.5\" data-el-top=\"0.2\" data-scroll-animation-off=\"1024\" data-id=\"b225c1f\" data-element_type=\"widget\" data-widget_type=\"aux_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-image aux-alignnone aux-parent-au145380f0\">\n    <div class=\"aux-media-hint-frame \">\n        <div class=\"aux-media-image \" >\n        \n            \n\n            \n            <img loading=\"lazy\" decoding=\"async\" width=\"370\" height=\"396\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/Gift-Left.png\" class=\"aux-attachment aux-featured-image aux-attachment-id-49\" alt=\"demo-attachment-1025-Gift-Left\" data-ratio=\"0.93\" data-original-w=\"370\" \/>            \n                <\/div>\n    <\/div>\n\n<\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-cf95661\" data-id=\"cf95661\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"aux-scroll-anim elementor-element elementor-element-c26ba0d elementor-widget elementor-widget-aux_image\" data-move-in=\"scale\" data-move-out=\"scale\" data-axis-x=\"200\" data-axis-y=\"200\" data-rotate=\"90\" data-scale=\"1.2\" data-vp-top=\"0.5\" data-vp-bot=\"0.5\" data-el-top=\"0.2\" data-scroll-animation-off=\"1024\" data-id=\"c26ba0d\" data-element_type=\"widget\" data-widget_type=\"aux_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-image aux-alignnone aux-parent-aud6612768\">\n    <div class=\"aux-media-hint-frame \">\n        <div class=\"aux-media-image \" >\n        \n            \n\n            \n            <img loading=\"lazy\" decoding=\"async\" width=\"684\" height=\"684\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/Ellipse-11.png\" class=\"aux-attachment aux-featured-image aux-attachment-id-55\" alt=\"demo-attachment-988-Ellipse-11\" data-ratio=\"1\" data-original-w=\"684\" \/>            \n                <\/div>\n    <\/div>\n\n<\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"aux-scroll-anim elementor-element elementor-element-b6038d3 elementor-widget__width-auto elementor-widget elementor-widget-aux_image\" data-move-in=\"moveHorizontal\" data-move-out=\"moveHorizontal\" data-axis-x=\"-30\" data-axis-y=\"200\" data-rotate=\"90\" data-scale=\"1\" data-vp-top=\"0.5\" data-vp-bot=\"0.5\" data-el-top=\"0.2\" data-scroll-animation-off=\"1024\" data-id=\"b6038d3\" data-element_type=\"widget\" data-widget_type=\"aux_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-image aux-alignnone aux-parent-au9b1bf673\">\n    <div class=\"aux-media-hint-frame \">\n        <div class=\"aux-media-image \" >\n        \n            \n\n            \n            <img loading=\"lazy\" decoding=\"async\" width=\"617\" height=\"886\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/Man-04.png\" class=\"aux-attachment aux-featured-image aux-attachment-id-278\" alt=\"Man-04\" data-ratio=\"0.7\" data-original-w=\"617\" \/>            \n                <\/div>\n    <\/div>\n\n<\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4979d87 elementor-widget__width-auto aux-shpe-type-circle elementor-widget elementor-widget-aux_simple_shape\" data-id=\"4979d87\" data-element_type=\"widget\" data-widget_type=\"aux_simple_shape.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t    <div class=\"aux-widget-container aux-simple-shape-container\">\n        <div class=\"aux-widget-container-inner\">\n            <div class=\"aux-the-shape\"><\/div>\n        <\/div>\n    <\/div>\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fefc6ab elementor-widget__width-auto aux-shpe-type-circle elementor-widget elementor-widget-aux_simple_shape\" data-id=\"fefc6ab\" data-element_type=\"widget\" data-widget_type=\"aux_simple_shape.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t    <div class=\"aux-widget-container aux-simple-shape-container\">\n        <div class=\"aux-widget-container-inner\">\n            <div class=\"aux-the-shape\"><\/div>\n        <\/div>\n    <\/div>\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"aux-scroll-anim elementor-element elementor-element-205a287 elementor-widget__width-auto elementor-widget elementor-widget-aux_image\" data-move-in=\"moveHorizontal\" data-move-out=\"moveHorizontal\" data-axis-x=\"-10\" data-axis-y=\"200\" data-rotate=\"90\" data-scale=\"1\" data-vp-top=\"0.5\" data-vp-bot=\"0.5\" data-el-top=\"0.2\" data-scroll-animation-off=\"1024\" data-id=\"205a287\" data-element_type=\"widget\" data-widget_type=\"aux_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-image aux-alignnone aux-parent-au3288569f\">\n    <div class=\"aux-media-hint-frame \">\n        <div class=\"aux-media-image \" >\n        \n            \n\n            \n            <img loading=\"lazy\" decoding=\"async\" width=\"273\" height=\"343\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/Group25.png\" class=\"aux-attachment aux-featured-image aux-attachment-id-52\" alt=\"demo-attachment-991-Group25\" data-ratio=\"0.8\" data-original-w=\"273\" \/>            \n                <\/div>\n    <\/div>\n\n<\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"aux-scroll-anim elementor-element elementor-element-3419ea2 elementor-widget__width-auto elementor-widget elementor-widget-aux_image\" data-move-in=\"rotateIn\" data-move-out=\"rotateIn\" data-axis-x=\"200\" data-axis-y=\"200\" data-rotate=\"15\" data-scale=\"1\" data-vp-top=\"0.5\" data-vp-bot=\"0.5\" data-el-top=\"0.2\" data-scroll-animation-off=\"1024\" data-id=\"3419ea2\" data-element_type=\"widget\" data-widget_type=\"aux_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-image aux-alignnone aux-parent-au27714761\">\n    <div class=\"aux-media-hint-frame \">\n        <div class=\"aux-media-image \" >\n        \n            \n\n            \n            <img loading=\"lazy\" decoding=\"async\" width=\"383\" height=\"366\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/Lock-Right.png\" class=\"aux-attachment aux-featured-image aux-attachment-id-51\" alt=\"demo-attachment-992-Lock-Right\" data-ratio=\"1.05\" data-original-w=\"383\" \/>            \n                <\/div>\n    <\/div>\n\n<\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"aux-scroll-anim elementor-element elementor-element-d362586 elementor-widget__width-auto elementor-widget elementor-widget-aux_image\" data-move-in=\"moveHorizontal\" data-move-out=\"moveHorizontal\" data-axis-x=\"25\" data-axis-y=\"200\" data-rotate=\"90\" data-scale=\"1\" data-vp-top=\"0.5\" data-vp-bot=\"0.5\" data-el-top=\"0.2\" data-scroll-animation-off=\"1024\" data-id=\"d362586\" data-element_type=\"widget\" data-widget_type=\"aux_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-image aux-alignnone aux-parent-au5e984545\">\n    <div class=\"aux-media-hint-frame \">\n        <div class=\"aux-media-image \" >\n        \n            \n\n            \n            <img loading=\"lazy\" decoding=\"async\" width=\"329\" height=\"468\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/Group.png\" class=\"aux-attachment aux-featured-image aux-attachment-id-54\" alt=\"demo-attachment-989-Group\" data-ratio=\"0.7\" data-original-w=\"329\" \/>            \n                <\/div>\n    <\/div>\n\n<\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5ca0d4 elementor-widget__width-auto aux-shpe-type-circle elementor-widget elementor-widget-aux_simple_shape\" data-id=\"f5ca0d4\" data-element_type=\"widget\" data-widget_type=\"aux_simple_shape.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t    <div class=\"aux-widget-container aux-simple-shape-container\">\n        <div class=\"aux-widget-container-inner\">\n            <div class=\"aux-the-shape\"><\/div>\n        <\/div>\n    <\/div>\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"aux-scroll-anim elementor-element elementor-element-d9768fe elementor-widget__width-auto elementor-widget elementor-widget-aux_image\" data-move-in=\"moveHorizontal\" data-move-out=\"moveHorizontal\" data-axis-x=\"15\" data-axis-y=\"200\" data-rotate=\"90\" data-scale=\"1\" data-vp-top=\"0.5\" data-vp-bot=\"0.5\" data-el-top=\"0.2\" data-scroll-animation-off=\"1024\" data-id=\"d9768fe\" data-element_type=\"widget\" data-widget_type=\"aux_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-image aux-alignnone aux-parent-au03662666\">\n    <div class=\"aux-media-hint-frame \">\n        <div class=\"aux-media-image \" >\n        \n            \n\n            \n            <img loading=\"lazy\" decoding=\"async\" width=\"366\" height=\"175\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/Group-2.png\" class=\"aux-attachment aux-featured-image aux-attachment-id-53\" alt=\"demo-attachment-990-Group-2\" data-ratio=\"2.09\" data-original-w=\"366\" \/>            \n                <\/div>\n    <\/div>\n\n<\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f345f59 elementor-widget__width-auto aux-shpe-type-circle elementor-widget elementor-widget-aux_simple_shape\" data-id=\"f345f59\" data-element_type=\"widget\" data-widget_type=\"aux_simple_shape.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t    <div class=\"aux-widget-container aux-simple-shape-container\">\n        <div class=\"aux-widget-container-inner\">\n            <div class=\"aux-the-shape\"><\/div>\n        <\/div>\n    <\/div>\n    \t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8fc2b0d elementor-section-full_width elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-height-default elementor-section-height-default\" data-id=\"8fc2b0d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cf033f5\" data-id=\"cf033f5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6997332 aux-appear-watch-animation aux-fade-in-up elementor-widget elementor-widget-aux_modern_heading\" data-id=\"6997332\" data-element_type=\"widget\" data-widget_type=\"aux_modern_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"aux-widget-modern-heading\">\n            <div class=\"aux-widget-inner\"><h5 class=\"aux-modern-heading-primary\">Testimonials<\/h5><h3 class=\"aux-modern-heading-secondary\"><span class=\"aux-head-highlight\">what customer say<\/span><\/h3><\/div>\n        <\/section>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3ff41c7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3ff41c7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c5a1ea5\" data-id=\"c5a1ea5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ec43fe aux-appear-watch-animation aux-fade-in-left-1 elementor-widget elementor-widget-aux_testimonial\" data-id=\"4ec43fe\" data-element_type=\"widget\" data-widget_type=\"aux_testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-testimonial-container aux-parent-au4ff1a9a8\">    <div class=\"  aux-widget-testimonial aux-testimonial-def-img \">\n                <div class=\"aux-testimonial-content\">\n            <div class=\"entry-content\">\n                                There are many variations of passages of Lorem Ipsum available, but the majority have suffered alteration in don't look slightly believable.            <\/div>\n        <\/div>\n                <div class=\"aux-testimonial-infobox\">\n                        <div class=\"aux-testimonial-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"65\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/134.jpg\" class=\"attachment-full size-full wp-image-48\" alt=\"\" \/>            <\/div>\n                        <div class=\"aux-testimonial-info\">\n                                <h4 class=\"col-title\">Samanta Willaian<\/h4>\n                                <h5 class=\"col-subtitle\">Home Cleaning<\/h5>\n                            <\/div>\n        <\/div>\n            <\/div>\n\n<\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-4ce853f\" data-id=\"4ce853f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cf09027 aux-appear-watch-animation aux-scale-down elementor-widget elementor-widget-aux_testimonial\" data-id=\"cf09027\" data-element_type=\"widget\" data-widget_type=\"aux_testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-testimonial-container aux-parent-au0f9f9110\">    <div class=\"  aux-widget-testimonial aux-testimonial-def-img \">\n                <div class=\"aux-testimonial-content\">\n            <div class=\"entry-content\">\n                                There are many variations of passages of Lorem Ipsum available, but the majority have suffered alteration in don't look slightly believable.            <\/div>\n        <\/div>\n                <div class=\"aux-testimonial-infobox\">\n                        <div class=\"aux-testimonial-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"65\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/12861.jpg\" class=\"attachment-full size-full wp-image-46\" alt=\"\" \/>            <\/div>\n                        <div class=\"aux-testimonial-info\">\n                                <h4 class=\"col-title\">David Famor<\/h4>\n                                <h5 class=\"col-subtitle\">Office Cleaning<\/h5>\n                            <\/div>\n        <\/div>\n            <\/div>\n\n<\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-013730d\" data-id=\"013730d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e702ef5 aux-appear-watch-animation aux-fade-in-right-1 elementor-widget elementor-widget-aux_testimonial\" data-id=\"e702ef5\" data-element_type=\"widget\" data-widget_type=\"aux_testimonial.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-testimonial-container aux-parent-au330c234e\">    <div class=\"  aux-widget-testimonial aux-testimonial-def-img \">\n                <div class=\"aux-testimonial-content\">\n            <div class=\"entry-content\">\n                                There are many variations of passages of Lorem Ipsum available, but the majority have suffered alteration in don't look slightly believable.            <\/div>\n        <\/div>\n                <div class=\"aux-testimonial-infobox\">\n                        <div class=\"aux-testimonial-image\">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"65\" height=\"65\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/10470.jpg\" class=\"attachment-full size-full wp-image-47\" alt=\"\" \/>            <\/div>\n                        <div class=\"aux-testimonial-info\">\n                                <h4 class=\"col-title\">Andrea Smith<\/h4>\n                                <h5 class=\"col-subtitle\">Bedroom Cleaning<\/h5>\n                            <\/div>\n        <\/div>\n            <\/div>\n\n<\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f2a4f18 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"f2a4f18\" data-element_type=\"section\" id=\"clients\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6ddc00e\" data-id=\"6ddc00e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"aux-scroll-anim elementor-element elementor-element-18341f1 elementor-widget__width-auto elementor-widget elementor-widget-aux_image\" data-move-in=\"moveHorizontal\" data-move-out=\"moveHorizontal\" data-axis-x=\"15\" data-axis-y=\"200\" data-rotate=\"90\" data-scale=\"1\" data-vp-top=\"0.5\" data-vp-bot=\"0.5\" data-el-top=\"0.2\" data-scroll-animation-off=\"1024\" data-id=\"18341f1\" data-element_type=\"widget\" data-widget_type=\"aux_image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"widget-container aux-widget-image aux-alignnone aux-parent-au3a0204a2\">\n    <div class=\"aux-media-hint-frame \">\n        <div class=\"aux-media-image \" >\n        \n            \n\n            \n            <img loading=\"lazy\" decoding=\"async\" width=\"334\" height=\"399\" src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2021\/08\/Pig-Right.png\" class=\"aux-attachment aux-featured-image aux-attachment-id-43\" alt=\"demo-attachment-1091-Pig-Right\" data-ratio=\"0.84\" data-original-w=\"334\" \/>            \n                <\/div>\n    <\/div>\n\n<\/section><!-- widget-container -->\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3fc6276 aux-appear-watch-animation aux-fade-in-up-1 elementor-widget elementor-widget-aux_modern_heading\" data-id=\"3fc6276\" data-element_type=\"widget\" data-widget_type=\"aux_modern_heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<section class=\"aux-widget-modern-heading\">\n            <div class=\"aux-widget-inner\"><h5 class=\"aux-modern-heading-primary\">Clients<\/h5><h3 class=\"aux-modern-heading-secondary\"><span class=\"aux-head-highlight\">Our Clients<\/span><\/h3><\/div>\n        <\/section>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-04314ae elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"04314ae\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b615246\" data-id=\"b615246\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-89b6df1 elementor-arrows-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"89b6df1\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;6&quot;,&quot;slides_to_scroll&quot;:&quot;2&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 25\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/1-1.png\" alt=\"1\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 25\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/2-1.png\" alt=\"2\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 25\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/3-1.png\" alt=\"3\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 25\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/4-1.png\" alt=\"4\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 25\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/5-1.png\" alt=\"5\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 25\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/6.png\" alt=\"6\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 25\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/7.png\" alt=\"7\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 25\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/8.png\" alt=\"8\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 25\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/9.png\" alt=\"9\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 25\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/10-1.png\" alt=\"10\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 of 25\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/11-1.png\" alt=\"11\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 of 25\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/12-1.png\" alt=\"12\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 of 25\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/13-1.png\" alt=\"13\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 of 25\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/14.png\" alt=\"14\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 of 25\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/15.png\" alt=\"15\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"16 of 25\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/16.png\" alt=\"16\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"17 of 25\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/17.png\" alt=\"17\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"18 of 25\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/18.png\" alt=\"18\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"19 of 25\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/19.png\" alt=\"19\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"20 of 25\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/20.png\" alt=\"20\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"21 of 25\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/21.png\" alt=\"21\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"22 of 25\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/22.png\" alt=\"22\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"23 of 25\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/23.png\" alt=\"23\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"24 of 25\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/24.png\" alt=\"24\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"25 of 25\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/25.png\" alt=\"25\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6a524dc elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6a524dc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"aux-parallax-section elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9a856c0\" data-id=\"9a856c0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-20d8f7a elementor-arrows-position-outside elementor-widget elementor-widget-image-carousel\" data-id=\"20d8f7a\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;6&quot;,&quot;slides_to_scroll&quot;:&quot;2&quot;,&quot;navigation&quot;:&quot;arrows&quot;,&quot;slides_to_show_mobile&quot;:&quot;1&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;autoplay_speed&quot;:5000,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper-container\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 of 28\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/26.png\" alt=\"26\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 of 28\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/27.png\" alt=\"27\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 of 28\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/28.png\" alt=\"28\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 of 28\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/29.png\" alt=\"29\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 of 28\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/30.png\" alt=\"30\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"6 of 28\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/31.png\" alt=\"31\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"7 of 28\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/32.png\" alt=\"32\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"8 of 28\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/33.png\" alt=\"33\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"9 of 28\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/34.png\" alt=\"34\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"10 of 28\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/35.png\" alt=\"35\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"11 of 28\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/36.png\" alt=\"36\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"12 of 28\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/37.png\" alt=\"37\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"13 of 28\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/38.png\" alt=\"38\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"14 of 28\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/39.png\" alt=\"39\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"15 of 28\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/40.png\" alt=\"40\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"16 of 28\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/41.png\" alt=\"41\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"17 of 28\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/42.png\" alt=\"42\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"18 of 28\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/43.png\" alt=\"43\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"19 of 28\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/44.png\" alt=\"44\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"20 of 28\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/45.png\" alt=\"45\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"21 of 28\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/46.png\" alt=\"46\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"22 of 28\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/47.png\" alt=\"47\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"23 of 28\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/48.png\" alt=\"48\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"24 of 28\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/49.png\" alt=\"49\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"25 of 28\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/50.png\" alt=\"50\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"26 of 28\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/51.png\" alt=\"51\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"27 of 28\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/52.png\" alt=\"52\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"28 of 28\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/aura-agency-eg.com\/wp-content\/uploads\/2023\/09\/Untitled-design-2.png\" alt=\"Untitled design (2)\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\" role=\"button\" tabindex=\"0\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>1 win We Are Taking You To A New World Of E-Marketing Aura Advertising Agency At aura advertising agency we are offers end-to-end solutions for your online presence, from branding your business, designing your website and optimizing it for higher rankings in search engine results to creating and executing complete digital marketing strategy for you. [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"templates\/page-builder-content.php","meta":{"footnotes":""},"class_list":["post-119","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/aura-agency-eg.com\/index.php\/wp-json\/wp\/v2\/pages\/119","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aura-agency-eg.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/aura-agency-eg.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/aura-agency-eg.com\/index.php\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/aura-agency-eg.com\/index.php\/wp-json\/wp\/v2\/comments?post=119"}],"version-history":[{"count":124,"href":"https:\/\/aura-agency-eg.com\/index.php\/wp-json\/wp\/v2\/pages\/119\/revisions"}],"predecessor-version":[{"id":1826,"href":"https:\/\/aura-agency-eg.com\/index.php\/wp-json\/wp\/v2\/pages\/119\/revisions\/1826"}],"wp:attachment":[{"href":"https:\/\/aura-agency-eg.com\/index.php\/wp-json\/wp\/v2\/media?parent=119"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}